{"id":2132,"date":"2019-06-13T11:32:00","date_gmt":"2019-06-13T02:32:00","guid":{"rendered":"http:\/\/lb-stg.linkedbrain.jp\/?page_id=2132"},"modified":"2019-07-05T14:02:44","modified_gmt":"2019-07-05T05:02:44","slug":"gamesolution","status":"publish","type":"page","link":"http:\/\/lb-stg.linkedbrain.jp\/zh\/service\/gamesolution\/","title":{"rendered":"\u904a\u6232\u89e3\u6c7a\u65b9\u6848"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":13,"featured_media":0,"parent":2129,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-noside.php","meta":{"_locale":"zh_TW","_original_post":"1949","footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-2132","page","type-page","status-publish","hentry","zh-TW"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u904a\u6232\u89e3\u6c7a\u65b9\u6848 - \u682a\u5f0f\u4f1a\u793e\u30ea\u30f3\u30af\u30c8\u30d6\u30ec\u30a4\u30f3<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u904a\u6232\u89e3\u6c7a\u65b9\u6848 - \u682a\u5f0f\u4f1a\u793e\u30ea\u30f3\u30af\u30c8\u30d6\u30ec\u30a4\u30f3\" \/>\n<meta property=\"og:url\" content=\"http:\/\/lb-stg.linkedbrain.jp\/zh\/service\/gamesolution\/\" \/>\n<meta property=\"og:site_name\" content=\"\u682a\u5f0f\u4f1a\u793e\u30ea\u30f3\u30af\u30c8\u30d6\u30ec\u30a4\u30f3\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-05T05:02:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/lb-stg.linkedbrain.jp\/zh\/service\/gamesolution\/\",\"url\":\"http:\/\/lb-stg.linkedbrain.jp\/zh\/service\/gamesolution\/\",\"name\":\"\u904a\u6232\u89e3\u6c7a\u65b9\u6848 - \u682a\u5f0f\u4f1a\u793e\u30ea\u30f3\u30af\u30c8\u30d6\u30ec\u30a4\u30f3\",\"isPartOf\":{\"@id\":\"https:\/\/lb-stg.linkedbrain.jp\/en\/#website\"},\"datePublished\":\"2019-06-13T02:32:00+00:00\",\"dateModified\":\"2019-07-05T05:02:44+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/lb-stg.linkedbrain.jp\/zh\/service\/gamesolution\/#breadcrumb\"},\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/lb-stg.linkedbrain.jp\/zh\/service\/gamesolution\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/lb-stg.linkedbrain.jp\/zh\/service\/gamesolution\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u30db\u30fc\u30e0\",\"item\":\"https:\/\/lb-stg.linkedbrain.jp\/zh\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u670d\u52d9\u9805\u76ee\",\"item\":\"http:\/\/lb-stg.linkedbrain.jp\/zh\/service\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u904a\u6232\u89e3\u6c7a\u65b9\u6848\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lb-stg.linkedbrain.jp\/en\/#website\",\"url\":\"https:\/\/lb-stg.linkedbrain.jp\/en\/\",\"name\":\"\u682a\u5f0f\u4f1a\u793e\u30ea\u30f3\u30af\u30c8\u30d6\u30ec\u30a4\u30f3\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/lb-stg.linkedbrain.jp\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lb-stg.linkedbrain.jp\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-TW\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lb-stg.linkedbrain.jp\/en\/#organization\",\"name\":\"\u682a\u5f0f\u4f1a\u793e\u30ea\u30f3\u30af\u30c8\u30d6\u30ec\u30a4\u30f3\",\"url\":\"https:\/\/lb-stg.linkedbrain.jp\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\/\/lb-stg.linkedbrain.jp\/en\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/lb-stg.linkedbrain.jp\/wp-content\/uploads\/2018\/05\/logo-1.png\",\"contentUrl\":\"http:\/\/lb-stg.linkedbrain.jp\/wp-content\/uploads\/2018\/05\/logo-1.png\",\"width\":155,\"height\":37,\"caption\":\"\u682a\u5f0f\u4f1a\u793e\u30ea\u30f3\u30af\u30c8\u30d6\u30ec\u30a4\u30f3\"},\"image\":{\"@id\":\"https:\/\/lb-stg.linkedbrain.jp\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u904a\u6232\u89e3\u6c7a\u65b9\u6848 - \u682a\u5f0f\u4f1a\u793e\u30ea\u30f3\u30af\u30c8\u30d6\u30ec\u30a4\u30f3","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"zh_TW","og_type":"article","og_title":"\u904a\u6232\u89e3\u6c7a\u65b9\u6848 - \u682a\u5f0f\u4f1a\u793e\u30ea\u30f3\u30af\u30c8\u30d6\u30ec\u30a4\u30f3","og_url":"http:\/\/lb-stg.linkedbrain.jp\/zh\/service\/gamesolution\/","og_site_name":"\u682a\u5f0f\u4f1a\u793e\u30ea\u30f3\u30af\u30c8\u30d6\u30ec\u30a4\u30f3","article_modified_time":"2019-07-05T05:02:44+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/lb-stg.linkedbrain.jp\/zh\/service\/gamesolution\/","url":"http:\/\/lb-stg.linkedbrain.jp\/zh\/service\/gamesolution\/","name":"\u904a\u6232\u89e3\u6c7a\u65b9\u6848 - \u682a\u5f0f\u4f1a\u793e\u30ea\u30f3\u30af\u30c8\u30d6\u30ec\u30a4\u30f3","isPartOf":{"@id":"https:\/\/lb-stg.linkedbrain.jp\/en\/#website"},"datePublished":"2019-06-13T02:32:00+00:00","dateModified":"2019-07-05T05:02:44+00:00","breadcrumb":{"@id":"http:\/\/lb-stg.linkedbrain.jp\/zh\/service\/gamesolution\/#breadcrumb"},"inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["http:\/\/lb-stg.linkedbrain.jp\/zh\/service\/gamesolution\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/lb-stg.linkedbrain.jp\/zh\/service\/gamesolution\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/lb-stg.linkedbrain.jp\/zh\/"},{"@type":"ListItem","position":2,"name":"\u670d\u52d9\u9805\u76ee","item":"http:\/\/lb-stg.linkedbrain.jp\/zh\/service\/"},{"@type":"ListItem","position":3,"name":"\u904a\u6232\u89e3\u6c7a\u65b9\u6848"}]},{"@type":"WebSite","@id":"https:\/\/lb-stg.linkedbrain.jp\/en\/#website","url":"https:\/\/lb-stg.linkedbrain.jp\/en\/","name":"\u682a\u5f0f\u4f1a\u793e\u30ea\u30f3\u30af\u30c8\u30d6\u30ec\u30a4\u30f3","description":"","publisher":{"@id":"https:\/\/lb-stg.linkedbrain.jp\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lb-stg.linkedbrain.jp\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-TW"},{"@type":"Organization","@id":"https:\/\/lb-stg.linkedbrain.jp\/en\/#organization","name":"\u682a\u5f0f\u4f1a\u793e\u30ea\u30f3\u30af\u30c8\u30d6\u30ec\u30a4\u30f3","url":"https:\/\/lb-stg.linkedbrain.jp\/en\/","logo":{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/lb-stg.linkedbrain.jp\/en\/#\/schema\/logo\/image\/","url":"http:\/\/lb-stg.linkedbrain.jp\/wp-content\/uploads\/2018\/05\/logo-1.png","contentUrl":"http:\/\/lb-stg.linkedbrain.jp\/wp-content\/uploads\/2018\/05\/logo-1.png","width":155,"height":37,"caption":"\u682a\u5f0f\u4f1a\u793e\u30ea\u30f3\u30af\u30c8\u30d6\u30ec\u30a4\u30f3"},"image":{"@id":"https:\/\/lb-stg.linkedbrain.jp\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"http:\/\/lb-stg.linkedbrain.jp\/wp-json\/wp\/v2\/pages\/2132"}],"collection":[{"href":"http:\/\/lb-stg.linkedbrain.jp\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/lb-stg.linkedbrain.jp\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/lb-stg.linkedbrain.jp\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"http:\/\/lb-stg.linkedbrain.jp\/wp-json\/wp\/v2\/comments?post=2132"}],"version-history":[{"count":1,"href":"http:\/\/lb-stg.linkedbrain.jp\/wp-json\/wp\/v2\/pages\/2132\/revisions"}],"predecessor-version":[{"id":2136,"href":"http:\/\/lb-stg.linkedbrain.jp\/wp-json\/wp\/v2\/pages\/2132\/revisions\/2136"}],"up":[{"embeddable":true,"href":"http:\/\/lb-stg.linkedbrain.jp\/wp-json\/wp\/v2\/pages\/2129"}],"wp:attachment":[{"href":"http:\/\/lb-stg.linkedbrain.jp\/wp-json\/wp\/v2\/media?parent=2132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}